{"id":987,"date":"2022-08-22T00:49:00","date_gmt":"2022-08-22T00:49:00","guid":{"rendered":"https:\/\/africafoodprize.org\/?page_id=987"},"modified":"2025-02-13T14:27:27","modified_gmt":"2025-02-13T14:27:27","slug":"home","status":"publish","type":"page","link":"https:\/\/africafoodprize.org\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-row-text-color=\"dark\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row zolo_wpb_row vc_row-fluid first-row-home-customized apress_row_class_18489364176a56efce64280 vc_custom_1661115671863 vc_row-has-fill vc_row-o-equal-height vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-4 vc_col-has-fill apress_col_id_3444552156a56efce648c1 hover_style_none\"><div class=\"layer vc_column-inner vc_custom_1661115255907\"  ><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 415px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8 apress_col_id_3633334596a56efce64d1d hover_style_none\"><div class=\"layer vc_column-inner vc_custom_1661115965946\"  ><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div style=\"color: #fff; font-size: 13px; line-height: 21px; max-width: 700px; \/*background-color: #0f7f4a;\">\n<h2 class=\"entry-title\" style=\"font-size: 25px; color: #fff; line-height: 1.4em;\">\u00c0 propos du<br \/>\n<strong style=\"font-size: 40px; font-weight: 600;\">Prix africain de l'alimentation<\/strong><\/h2>\n<p>Le Prix de l'alimentation en Afrique est la r\u00e9compense la plus prestigieuse d\u00e9cern\u00e9e \u00e0 une personne ou une institution exceptionnelle qui contribue \u00e0 changer la r\u00e9alit\u00e9 de l'agriculture en Afrique - d'une lutte pour la survie \u00e0 une activit\u00e9 \u00e9conomique rentable.<\/p>\n<p>Le prix, d'un montant de 100 000 dollars, rend hommage aux Africains qui prennent en main l\u2019agenda agricole du continent. Ce prix met l'accent sur les initiatives audacieuses et les innovations techniques qui peuvent \u00eatre reproduites sur tout le continent afin de cr\u00e9er une nouvelle \u00e8re de s\u00e9curit\u00e9 alimentaire et d'opportunit\u00e9s \u00e9conomiques pour tous les Africains.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n<div id=\"zolo_button_element_18726087046a56efce650e0\" class=\"zolo_button_element zolo_button_left zolo_button_hoverstyle4 design_your_own noanimation\" data-animation = \"No Animation\" data-delay = \"500\"><a href=\"https:\/\/africafoodprize.org\/fr\/about\/\" title=\"A propos du prix\" class=\"zolo_button zolo_button_round zolo_button_size_medium zolo_ripplelink\"><span class=\"zolo_button_text\" style=\"\">Cliquez ici pour en savoir plus<\/span><\/a><\/div>    \r\n <style>   \r\n \r\n\r\n#zolo_button_element_18726087046a56efce650e0 .zolo_button.zolo_button_size_design_your_own{padding:15px 25px;}\r\n\r\n\/*Design Your Won CSS Start*\/\r\n#zolo_button_element_18726087046a56efce650e0.zolo_button_hoverstyle6 .zolo_button,\r\n#zolo_button_element_18726087046a56efce650e0.zolo_button_hoverstyle1 .zolo_button,\r\n#zolo_button_element_18726087046a56efce650e0 .zolo_button{background:#e5f242;color:#0f7f4a;border-color:#e5f242;}\r\n\r\n#zolo_button_element_18726087046a56efce650e0 .zolo_button:focus,\r\n#zolo_button_element_18726087046a56efce650e0 .zolo_button:hover{color:#ffffff;}\r\n\r\n#zolo_button_element_18726087046a56efce650e0.zolo_button_hoverstyle6 .zolo_button:hover,\r\n#zolo_button_element_18726087046a56efce650e0.zolo_button_hoverstyle1 .zolo_button:hover,\r\n#zolo_button_element_18726087046a56efce650e0 .zolo_button:after{background:#0f7f4a;color:#ffffff; border-color:#0F7F4A;}\r\n\r\n\/*Design Your Won CSS End*\/\r\n\r\n<\/style>\r\n\r\n\r\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-row-text-color=\"dark\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row zolo_wpb_row vc_row-fluid fancy-white-bg-section apress_row_class_18129849726a56efce65747 vc_custom_1661124084226\"><div class=\"wpb_column vc_column_container vc_col-sm-12 apress_col_id_19021788806a56efce65a10 hover_style_none\"><div class=\"layer vc_column-inner\"  ><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 90px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\t\r\n<div id=\"zolo_heading_element_9995941756a56efce65d8d\" class=\"zolo_heading_element heading_style1 noanimation\" data-animation = \"No Animation\" data-delay = \"500\" style=\" text-align:left\"><div class=\"zolo_heading_element_text\"><h2 class=\"zolo-title\"><span class=\"title_text\" style=\"font-size: 40px; font-weight:bold; \">Laur\u00e9ats du prix<\/span><\/h2><p class=\"zolo-sub-title\" style=\"font-size: 13px; \"><span class=\"zolo-sub-title-text\">Repr\u00e9sentant un large \u00e9ventail de la soci\u00e9t\u00e9 africaine, les laur\u00e9ats du prix sont des entrepreneurs, des scientifiques, des organisateurs et des militants communautaires, des chefs d'entreprise et des d\u00e9cideurs politiques, qui contribuent tous, de mani\u00e8re diverse et efficace, \u00e0 une r\u00e9volution verte en AfriqueI qui renforce le d\u00e9veloppement agricole et la s\u00e9curit\u00e9 alimentaire du continent.<\/span><\/p><\/div><\/div>\r\n<style>\r\n#zolo_heading_element_9995941756a56efce65d8d .zolo-title {}#zolo_heading_element_9995941756a56efce65d8d .zolo-sub-title {}#zolo_heading_element_9995941756a56efce65d8d .zolo-heading-delimiter {}\/*Design Your Won CSS Start*\/\r\n#zolo_heading_element_9995941756a56efce65d8d .zolo-title span.title_text{color:#d6473a;}\r\n\r\n\/*Design Your Won CSS End*\/\r\n#zolo_heading_element_9995941756a56efce65d8d.heading_style11 .zolo-sub-title span.zolo-sub-title-text,\r\n#zolo_heading_element_9995941756a56efce65d8d.heading_style12 .zolo-sub-title span.zolo-sub-title-text{ background:#f2f2f2; padding:7px 15px;}\r\n\r\n#zolo_heading_element_9995941756a56efce65d8d .delimiter_style_line { display:inline-block; border-bottom:3px solid ;width:80px;}\r\n\r\n#zolo_heading_element_9995941756a56efce65d8d .zolo_icon{ font-size:30px; color:;}\r\n#zolo_heading_element_9995941756a56efce65d8d .zolo_icon.circle_background,\r\n#zolo_heading_element_9995941756a56efce65d8d .zolo_icon.square_background{ background:#eeeeee;}\r\n\r\n#zolo_heading_element_9995941756a56efce65d8d .zolo_icon.design_your_own{ width:50px; height:50px;line-height:50px;background:#eeeeee;border:1px  #eaeaea;\r\n-moz-border-radius:300px;-webkit-border-radius:300px;-ms-border-radius:300px;-o-border-radius:300px;border-radius:300px;}\r\n\r\n\r\n#zolo_heading_element_9995941756a56efce65d8d .space_between_line_icon{ padding:0 20px; display:inline-block; position:relative;}\r\n\r\n#zolo_heading_element_9995941756a56efce65d8d .space_between_line_icon:before,\r\n#zolo_heading_element_9995941756a56efce65d8d .space_between_line_icon:after{border-bottom:3px solid ;width:80px;\r\n}\r\n<\/style>\r\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"green-ult wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-new-ib ult-ib-effect-style2  ult-ib-resp ult-ib2-min-height\" data-min-width=\"768\" data-max-width=\"900\" style=\" opacity:0; \" data-opacity=\"1\" data-hover-opacity=\"1\"  data-min-height=\"330\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:1;\" alt=\"null\" src=\"https:\/\/africafoodprize.org\/wp-content\/uploads\/2025\/01\/IMG_9016-3-scaled.jpg\"  data-min-height=\"330\"   \/><div id=\"interactive-banner-wrap-6456\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-6456 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">Africa Food Prize Winner 2024<\/h2><div class=\"ult-new-ib-content ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-6456 .ult-new-ib-content'  data-responsive-json-new='{\"font-size\":\"desktop:14px;\",\"line-height\":\"\"}'  style=\"font-weight:normal;\"><p>Winner 2024<\/p><\/div><\/div><a class=\"ult-new-ib-link\" href=\"https:\/\/africafoodprize.org\/fr\/tinotenda-mhiko-ceo-of-zimbabwes-arda-wins-2024-africa-food-prize-for-excellence-in-agricultural-leadership\/\" title=\"Pan-Africa Bean Research Alliance (PABRA)\" target=\"_blank\" rel=\"noopener\"  ><\/a><\/div><div class=\"ult-new-ib ult-ib-effect-style2  ult-ib-resp ult-ib2-min-height\" data-min-width=\"768\" data-max-width=\"900\" style=\" opacity:0; \" data-opacity=\"1\" data-hover-opacity=\"1\"  data-min-height=\"330\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:1;\" alt=\"null\" src=\"https:\/\/africafoodprize.org\/wp-content\/uploads\/2022\/08\/afp-2021-winners-icrisat.jpg\"  data-min-height=\"330\"   \/><div id=\"interactive-banner-wrap-7622\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-7622 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">ICRISAT<\/h2><div class=\"ult-new-ib-content ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-7622 .ult-new-ib-content'  data-responsive-json-new='{\"font-size\":\"desktop:14px;\",\"line-height\":\"\"}'  style=\"font-weight:normal;\"><p>Gagnant 2021<\/p><\/div><\/div><a class=\"ult-new-ib-link\" href=\"https:\/\/africafoodprize.org\/fr\/icrisat-awarded-2021-africa-food-prize\/\" title=\"ICRISAT Awarded 2021 AFP\"  ><\/a><\/div><\/div><\/div><\/div><div class=\"orange-ult wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-new-ib ult-ib-effect-style2  ult-ib-resp ult-ib2-min-height\" data-min-width=\"768\" data-max-width=\"900\" style=\" opacity:0; \" data-opacity=\"1\" data-hover-opacity=\"1\"  data-min-height=\"330\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:1;\" alt=\"null\" src=\"https:\/\/africafoodprize.org\/wp-content\/uploads\/2023\/09\/PABRA-Logo-1.jpg\"  data-min-height=\"330\"   \/><div id=\"interactive-banner-wrap-1457\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-1457 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">Pan-Africa Bean Research Alliance (PABRA)<\/h2><div class=\"ult-new-ib-content ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-1457 .ult-new-ib-content'  data-responsive-json-new='{\"font-size\":\"desktop:14px;\",\"line-height\":\"\"}'  style=\"font-weight:normal;\"><p>Winner 2023<\/p><\/div><\/div><a class=\"ult-new-ib-link\" href=\"https:\/\/africafoodprize.org\/fr\/pan-africa-bean-research-alliance-pabra-wins-africa-food-prize-2023\/\" title=\"Pan-Africa Bean Research Alliance (PABRA)\"  ><\/a><\/div><\/div><\/div><\/div><div class=\"lightgreen-ult wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"ult-new-ib ult-ib-effect-style2  ult-ib-resp ult-ib2-min-height\" data-min-width=\"768\" data-max-width=\"900\" style=\" opacity:0; \" data-opacity=\"1\" data-hover-opacity=\"1\"  data-min-height=\"330\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:1;\" alt=\"null\" src=\"https:\/\/africafoodprize.org\/wp-content\/uploads\/2022\/09\/Prof.-Danquah.jpg\"  data-min-height=\"330\"   \/><div id=\"interactive-banner-wrap-3672\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-3672 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">Dr Eric Yirenkyi Danquah<\/h2><div class=\"ult-new-ib-content ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-3672 .ult-new-ib-content'  data-responsive-json-new='{\"font-size\":\"desktop:14px;\",\"line-height\":\"\"}'  style=\"font-weight:normal;\"><p>Gagnant 2022<\/p><\/div><\/div><a class=\"ult-new-ib-link\" href=\"https:\/\/africafoodprize.org\/fr\/africa-food-prize-winner-2022-announced\/\" title=\"Eric Yirenkyi Danquah\"  ><\/a><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\r\n\r\n<div id=\"zolo_button_element_18226584556a56efce66f02\" class=\"zolo_button_element zolo_button_center zolo_button_hoverstyle4 design_your_own noanimation\" data-animation = \"No Animation\" data-delay = \"500\"><a href=\"https:\/\/africafoodprize.org\/fr\/laureates\/\" title=\"A propos du prix\" class=\"zolo_button zolo_button_round zolo_button_size_medium zolo_ripplelink\"><span class=\"zolo_button_text\" style=\"\">Voir tous les laur\u00e9ats<\/span><\/a><\/div>    \r\n <style>   \r\n \r\n\r\n#zolo_button_element_18226584556a56efce66f02 .zolo_button.zolo_button_size_design_your_own{padding:15px 25px;}\r\n\r\n\/*Design Your Won CSS Start*\/\r\n#zolo_button_element_18226584556a56efce66f02.zolo_button_hoverstyle6 .zolo_button,\r\n#zolo_button_element_18226584556a56efce66f02.zolo_button_hoverstyle1 .zolo_button,\r\n#zolo_button_element_18226584556a56efce66f02 .zolo_button{background:#e5f242;color:#0f7f4a;border-color:#e5f242;}\r\n\r\n#zolo_button_element_18226584556a56efce66f02 .zolo_button:focus,\r\n#zolo_button_element_18226584556a56efce66f02 .zolo_button:hover{color:#ffffff;}\r\n\r\n#zolo_button_element_18226584556a56efce66f02.zolo_button_hoverstyle6 .zolo_button:hover,\r\n#zolo_button_element_18226584556a56efce66f02.zolo_button_hoverstyle1 .zolo_button:hover,\r\n#zolo_button_element_18226584556a56efce66f02 .zolo_button:after{background:#0f7f4a;color:#ffffff; border-color:#0f7f4a;}\r\n\r\n\/*Design Your Won CSS End*\/\r\n\r\n<\/style>\r\n\r\n\r\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-row-text-color=\"dark\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row zolo_wpb_row vc_row-fluid apress_row_class_15381790786a56efce6727c vc_custom_1680073768676 vc_row-has-fill\"><div class=\"committee-title wpb_column vc_column_container vc_col-sm-4 apress_col_id_11356666776a56efce67543 hover_style_none\"><div class=\"layer vc_column-inner\"  ><div class=\"wpb_wrapper\">\t\r\n<div id=\"zolo_heading_element_20883419416a56efce67740\" class=\"zolo_heading_element heading_style1 noanimation\" data-animation = \"No Animation\" data-delay = \"500\" style=\" text-align:right\"><div class=\"zolo_heading_element_text\"><h3 class=\"zolo-title\"><span class=\"title_text\" style=\"font-size: 40px; line-height: 30px; \"><span style=\"font-size: 30px;\">Prix africain de l'alimentation<\/span><br \/>\n<strong>Le Comit\u00e9<\/strong><\/span><\/h3><\/div><\/div>\r\n<style>\r\n#zolo_heading_element_20883419416a56efce67740 .zolo-title {}#zolo_heading_element_20883419416a56efce67740 .zolo-sub-title {}#zolo_heading_element_20883419416a56efce67740 .zolo-heading-delimiter {}\/*Design Your Won CSS Start*\/\r\n#zolo_heading_element_20883419416a56efce67740 .zolo-title span.title_text{color:#ffffff;}\r\n\r\n\/*Design Your Won CSS End*\/\r\n#zolo_heading_element_20883419416a56efce67740.heading_style11 .zolo-sub-title span.zolo-sub-title-text,\r\n#zolo_heading_element_20883419416a56efce67740.heading_style12 .zolo-sub-title span.zolo-sub-title-text{ background:#f2f2f2; padding:7px 15px;}\r\n\r\n#zolo_heading_element_20883419416a56efce67740 .delimiter_style_line { display:inline-block; border-bottom:3px solid ;width:80px;}\r\n\r\n#zolo_heading_element_20883419416a56efce67740 .zolo_icon{ font-size:30px; color:;}\r\n#zolo_heading_element_20883419416a56efce67740 .zolo_icon.circle_background,\r\n#zolo_heading_element_20883419416a56efce67740 .zolo_icon.square_background{ background:#eeeeee;}\r\n\r\n#zolo_heading_element_20883419416a56efce67740 .zolo_icon.design_your_own{ width:50px; height:50px;line-height:50px;background:#eeeeee;border:1px  #eaeaea;\r\n-moz-border-radius:300px;-webkit-border-radius:300px;-ms-border-radius:300px;-o-border-radius:300px;border-radius:300px;}\r\n\r\n\r\n#zolo_heading_element_20883419416a56efce67740 .space_between_line_icon{ padding:0 20px; display:inline-block; position:relative;}\r\n\r\n#zolo_heading_element_20883419416a56efce67740 .space_between_line_icon:before,\r\n#zolo_heading_element_20883419416a56efce67740 .space_between_line_icon:after{border-bottom:3px solid ;width:80px;\r\n}\r\n<\/style>\r\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 apress_col_id_20580275806a56efce67999 hover_style_none\"><div class=\"layer vc_column-inner\"  ><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1680073890369\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"color: white;\">Le Comit\u00e9 du Prix africain de l'alimentation est un organisme ind\u00e9pendant pr\u00e9sid\u00e9 par l'ancien pr\u00e9sident nig\u00e9rian, H.E Jakaya Mrisho Kikwete.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n<div id=\"zolo_button_element_1407628856a56efce67c0e\" class=\"zolo_button_element zolo_button_left zolo_button_hoverstyle1 design_your_own noanimation\" data-animation = \"No Animation\" data-delay = \"500\"><a href=\"https:\/\/africafoodprize.org\/fr\/committee\/\" title=\"A propos du prix\" class=\"zolo_button zolo_button_round zolo_button_size_medium zolo_ripplelink\"><span class=\"zolo_button_text\" style=\"\">En savoir plus sur le comit\u00e9<\/span><\/a><\/div>    \r\n <style>   \r\n \r\n\r\n#zolo_button_element_1407628856a56efce67c0e .zolo_button.zolo_button_size_design_your_own{padding:15px 25px;}\r\n\r\n\/*Design Your Won CSS Start*\/\r\n#zolo_button_element_1407628856a56efce67c0e.zolo_button_hoverstyle6 .zolo_button,\r\n#zolo_button_element_1407628856a56efce67c0e.zolo_button_hoverstyle1 .zolo_button,\r\n#zolo_button_element_1407628856a56efce67c0e .zolo_button{background:#d6473a;color:#ffffff;border-color:;}\r\n\r\n#zolo_button_element_1407628856a56efce67c0e .zolo_button:focus,\r\n#zolo_button_element_1407628856a56efce67c0e .zolo_button:hover{color:#ffffff;}\r\n\r\n#zolo_button_element_1407628856a56efce67c0e.zolo_button_hoverstyle6 .zolo_button:hover,\r\n#zolo_button_element_1407628856a56efce67c0e.zolo_button_hoverstyle1 .zolo_button:hover,\r\n#zolo_button_element_1407628856a56efce67c0e .zolo_button:after{background:#a32727;color:#ffffff; border-color:;}\r\n\r\n\/*Design Your Won CSS End*\/\r\n\r\n<\/style>\r\n\r\n\r\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 apress_col_id_289138176a56efce67e31 hover_style_none\"><div class=\"layer vc_column-inner\"  ><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-row-text-color=\"dark\" class=\"vc_row wpb_row zolo_wpb_row vc_row-fluid apress_row_class_7613869536a56efce68115\"><div class=\"wpb_column vc_column_container vc_col-sm-12 apress_col_id_6109973256a56efce6843f hover_style_none\"><div class=\"layer vc_column-inner\"  ><div class=\"wpb_wrapper\">\t\r\n<div id=\"zolo_heading_element_683373916a56efce686fd\" class=\"zolo_heading_element heading_style1 noanimation\" data-animation = \"No Animation\" data-delay = \"500\" style=\" text-align:left\"><div class=\"zolo_heading_element_text\"><h2 class=\"zolo-title\"><span class=\"title_text\" style=\"font-size: 40px; font-weight:bold; \">Actualit\u00e9s et mises \u00e0 jour<\/span><\/h2><\/div><\/div>\r\n<style>\r\n#zolo_heading_element_683373916a56efce686fd .zolo-title {}#zolo_heading_element_683373916a56efce686fd .zolo-sub-title {}#zolo_heading_element_683373916a56efce686fd .zolo-heading-delimiter {}\/*Design Your Won CSS Start*\/\r\n#zolo_heading_element_683373916a56efce686fd .zolo-title span.title_text{color:#d6473a;}\r\n\r\n\/*Design Your Won CSS End*\/\r\n#zolo_heading_element_683373916a56efce686fd.heading_style11 .zolo-sub-title span.zolo-sub-title-text,\r\n#zolo_heading_element_683373916a56efce686fd.heading_style12 .zolo-sub-title span.zolo-sub-title-text{ background:#f2f2f2; padding:7px 15px;}\r\n\r\n#zolo_heading_element_683373916a56efce686fd .delimiter_style_line { display:inline-block; border-bottom:3px solid ;width:80px;}\r\n\r\n#zolo_heading_element_683373916a56efce686fd .zolo_icon{ font-size:30px; color:;}\r\n#zolo_heading_element_683373916a56efce686fd .zolo_icon.circle_background,\r\n#zolo_heading_element_683373916a56efce686fd .zolo_icon.square_background{ background:#eeeeee;}\r\n\r\n#zolo_heading_element_683373916a56efce686fd .zolo_icon.design_your_own{ width:50px; height:50px;line-height:50px;background:#eeeeee;border:1px  #eaeaea;\r\n-moz-border-radius:300px;-webkit-border-radius:300px;-ms-border-radius:300px;-o-border-radius:300px;border-radius:300px;}\r\n\r\n\r\n#zolo_heading_element_683373916a56efce686fd .space_between_line_icon{ padding:0 20px; display:inline-block; position:relative;}\r\n\r\n#zolo_heading_element_683373916a56efce686fd .space_between_line_icon:before,\r\n#zolo_heading_element_683373916a56efce686fd .space_between_line_icon:after{border-bottom:3px solid ;width:80px;\r\n}\r\n<\/style>\r\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<script type=\"text\/javascript\" charset=\"utf-8\">\r\n\t\t\tjQuery.noConflict();\r\n\t\t\tvar j$ = jQuery;\r\n\t\t\t\"use strict\";\r\n\t\t\tj$(window).load(function() {\r\n\t\t\tvar $container = j$(\".site-content.ni29aouiocgzmads1um2shortcode_blog_layout_masonry\");\t\r\n\t\t\tvar $grid = $container.imagesLoaded( function() {\r\n\t\t\t\t\t\/\/ init Isotope\r\n\t\t\t\t\t$container.isotope({\r\n\t\t\t\t\t\/\/ options\r\n\t\t\t\t\t\titemSelector : '.masonry-item',\r\n\t\t\t\t\t\tlayoutMode : 'masonry'\r\n\t\t\t\t\t})\r\n\t\t\t\t});\r\n\t\t\t\t\/\/ filter functions\r\n\t\t\t\t  var filterFns = {\r\n\t\t\t\t\t\/\/ show if number is greater than 50\r\n\t\t\t\t\tnumberGreaterThan50: function() {\r\n\t\t\t\t\t  var number = j$(this).find('.number').text();\r\n\t\t\t\t\t  return parseInt( number, 10 ) > 50;\r\n\t\t\t\t\t},\r\n\t\t\t\t\t\/\/ show if name ends with -ium\r\n\t\t\t\t\tium: function() {\r\n\t\t\t\t\t  var name = j$(this).find('.name').text();\r\n\t\t\t\t\t  return name.match( \/ium$\/ );\r\n\t\t\t\t\t}\r\n\t\t\t\t  };\r\n\t\t\t\t  \/\/ bind filter button click\r\n\t\t\t\t  j$('.postfilter-ni29aouiocgzmads1um2').on( 'click', 'button', function() {\r\n\t\t\t\t\tvar filterValue = j$( this ).attr('data-filter');\r\n\t\t\t\t\t\/\/ use filterFn if matches value\r\n\t\t\t\t\tfilterValue = filterFns[ filterValue ] || filterValue;\r\n\t\t\t\t\t$grid.isotope({ filter: filterValue });\r\n\t\t\t\t  });\r\n\t\t\t\t  \/\/ change is-checked class on buttons\r\n\t\t\t\t  j$('.postfilter-ni29aouiocgzmads1um2').each( function( i, buttonGroup ) {\r\n\t\t\t\t\tvar $buttonGroup = j$( buttonGroup );\r\n\t\t\t\t\t$buttonGroup.on( 'click', 'button', function() {\r\n\t\t\t\t\t  $buttonGroup.find('.is-checked').removeClass('is-checked');\r\n\t\t\t\t\t  j$( this ).addClass('is-checked');\r\n\t\t\t\t\t});\r\n\t\t\t\t  });\t\t\t\t\r\n\t\t\t});\r\n\t\t<\/script>\r\n\t\t\t\t\r\n\t\t<!--Blog Row Start-->\r\n\t\t\r\n\t\t<div class=\"zolo_blog_area  zoloblogstyleacp_2553290736a56efce696de zolo_blog_style1 zolo_blog_vertical none\">\r\n\t\t\t\t\t\t  <div class=\"zolo_blog_row\" style=\"margin:0px -px 0 -px;\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"zolo_row site-content ni29aouiocgzmads1um2shortcode_blog_layout_masonry\">\r\n\t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \r\n\t\t\t  <!--Blog Box Area Start-->\r\n\t\t\t  \r\n\t\t\t  <div class=\"zolo_blog_col zolo_blog_col3 masonry-item   noanimation\" style=\"padding:20px px px px;\" data-animation=\"No Animation\" data-delay=\"500\">\r\n\t\t\t\t<div class=\"zolo_blog_box\" style=\"background:#d6473a; border-color:; border-radius:0px;\">\r\n\t\t\t\t  \t\t\t\t  \t\t\t\t  \r\n\t\t\t\t  <!--Thumb Area Start-->\r\n\t\t\t\t  \r\n\t\t\t\t  <div class=\"zolo_blog_thumb\">\r\n\t\t\t\t\t<span class=\"zolo_zilla_likes_box\"> <a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-1466\" title=\"Like this\"><i class=\"fa fa-heart-o\"><\/i> <span class=\"zilla-likes-count\">0<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/span>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/africafoodprize.org\/wp-content\/uploads\/2025\/02\/new-nomination.jpg\" \/> <span class=\"overlay\"><\/span> \r\n\t\t\t\t\t<!--Style 1 Icons Area Start-->\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"zolo_blog_icons\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 1 Icons Area End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 3 Title Start-->\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 3 Title End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 4 Blog Detail Area Start-->\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 4 Blog Detail Area End-->\r\n\t\t\t\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t  \r\n\t\t\t\t  <!--Thumb Area End--> \r\n\t\t\t\t  \r\n\t\t\t\t  <!--Style 1, 2 & 3 Blog Detail Area Start-->\r\n\t\t\t\t  \t\t\t\t  <div class=\"zolo_blog_detail\"> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 1 & 2 Title Start-->\r\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"zolo_blog_title entry-title\" style=\"color:#ffffff;font-size:24px;\"> <a href=\"https:\/\/africafoodprize.org\/fr\/tinotenda-mhiko-ceo-of-zimbabwes-arda-wins-2024-africa-food-prize-for-excellence-in-agricultural-leadership-2\/\" style=\"color:#ffffff;\">\r\n\t\t\t\t\t  Africa Food Prize 2025 Call for Nominations Now Open\t\t\t\t\t  <\/a> <\/h2>\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 1 & 2 Title End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 1 Meta Tag Start-->\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"zolo_blog_date\" style=\"color:#ffffff;\">\r\n\t\t\t\t\tf\u00e9vrier 14th, 2025\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 1 Meta Tag End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 2 Meta Tag Start-->\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 2 Meta Tag End--> \r\n\t\t\t\t\t<!--Style 2 Meta Tag Start-->\r\n\t\t\t\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t  \t\t\t\t  <!--Style 1 & 2 Blog Detail Area End--> \r\n\t\t\t\t  \r\n\t\t\t\t<\/div>\r\n\t\t\t  <\/div>\r\n\t\t\t  <!--Blog Box Area End-->\r\n\t\t\t  \r\n\t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \r\n\t\t\t  <!--Blog Box Area Start-->\r\n\t\t\t  \r\n\t\t\t  <div class=\"zolo_blog_col zolo_blog_col3 masonry-item   noanimation\" style=\"padding:20px px px px;\" data-animation=\"No Animation\" data-delay=\"500\">\r\n\t\t\t\t<div class=\"zolo_blog_box\" style=\"background:#d6473a; border-color:; border-radius:0px;\">\r\n\t\t\t\t  \t\t\t\t  \t\t\t\t  \r\n\t\t\t\t  <!--Thumb Area Start-->\r\n\t\t\t\t  \r\n\t\t\t\t  <div class=\"zolo_blog_thumb\">\r\n\t\t\t\t\t<span class=\"zolo_zilla_likes_box\"> <a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-1411\" title=\"Like this\"><i class=\"fa fa-heart-o\"><\/i> <span class=\"zilla-likes-count\">0<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/span>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/africafoodprize.org\/wp-content\/uploads\/2025\/01\/IMG_9016-3-scaled.jpg\" \/> <span class=\"overlay\"><\/span> \r\n\t\t\t\t\t<!--Style 1 Icons Area Start-->\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"zolo_blog_icons\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 1 Icons Area End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 3 Title Start-->\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 3 Title End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 4 Blog Detail Area Start-->\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 4 Blog Detail Area End-->\r\n\t\t\t\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t  \r\n\t\t\t\t  <!--Thumb Area End--> \r\n\t\t\t\t  \r\n\t\t\t\t  <!--Style 1, 2 & 3 Blog Detail Area Start-->\r\n\t\t\t\t  \t\t\t\t  <div class=\"zolo_blog_detail\"> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 1 & 2 Title Start-->\r\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"zolo_blog_title entry-title\" style=\"color:#ffffff;font-size:24px;\"> <a href=\"https:\/\/africafoodprize.org\/fr\/tinotenda-mhiko-ceo-of-zimbabwes-arda-wins-2024-africa-food-prize-for-excellence-in-agricultural-leadership\/\" style=\"color:#ffffff;\">\r\n\t\t\t\t\t  Tinotenda Mhiko, CEO of Zimbabwe&#8217;s ARDA, Wins 2024 Africa Food Prize for Excellence in Agricultural Leadership\t\t\t\t\t  <\/a> <\/h2>\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 1 & 2 Title End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 1 Meta Tag Start-->\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"zolo_blog_date\" style=\"color:#ffffff;\">\r\n\t\t\t\t\tseptembre 5th, 2024\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 1 Meta Tag End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 2 Meta Tag Start-->\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 2 Meta Tag End--> \r\n\t\t\t\t\t<!--Style 2 Meta Tag Start-->\r\n\t\t\t\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t  \t\t\t\t  <!--Style 1 & 2 Blog Detail Area End--> \r\n\t\t\t\t  \r\n\t\t\t\t<\/div>\r\n\t\t\t  <\/div>\r\n\t\t\t  <!--Blog Box Area End-->\r\n\t\t\t  \r\n\t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \r\n\t\t\t  <!--Blog Box Area Start-->\r\n\t\t\t  \r\n\t\t\t  <div class=\"zolo_blog_col zolo_blog_col3 masonry-item   noanimation\" style=\"padding:20px px px px;\" data-animation=\"No Animation\" data-delay=\"500\">\r\n\t\t\t\t<div class=\"zolo_blog_box\" style=\"background:#d6473a; border-color:; border-radius:0px;\">\r\n\t\t\t\t  \t\t\t\t  \t\t\t\t  \r\n\t\t\t\t  <!--Thumb Area Start-->\r\n\t\t\t\t  \r\n\t\t\t\t  <div class=\"zolo_blog_thumb\">\r\n\t\t\t\t\t<span class=\"zolo_zilla_likes_box\"> <a href=\"#\" class=\"zilla-likes\" id=\"zilla-likes-1378\" title=\"Like this\"><i class=\"fa fa-heart-o\"><\/i> <span class=\"zilla-likes-count\">0<\/span> <span class=\"zilla-likes-postfix\"><\/span><\/a><\/span>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/africafoodprize.org\/wp-content\/uploads\/2024\/02\/AFP-Press-Release-1.jpg\" \/> <span class=\"overlay\"><\/span> \r\n\t\t\t\t\t<!--Style 1 Icons Area Start-->\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"zolo_blog_icons\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 1 Icons Area End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 3 Title Start-->\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 3 Title End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 4 Blog Detail Area Start-->\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 4 Blog Detail Area End-->\r\n\t\t\t\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t  \r\n\t\t\t\t  <!--Thumb Area End--> \r\n\t\t\t\t  \r\n\t\t\t\t  <!--Style 1, 2 & 3 Blog Detail Area Start-->\r\n\t\t\t\t  \t\t\t\t  <div class=\"zolo_blog_detail\"> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 1 & 2 Title Start-->\r\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"zolo_blog_title entry-title\" style=\"color:#ffffff;font-size:24px;\"> <a href=\"https:\/\/africafoodprize.org\/fr\/africa-food-prize-2024-call-for-nominations-now-open\/\" style=\"color:#ffffff;\">\r\n\t\t\t\t\t  Africa Food Prize 2024 Call for Nominations Now Open\t\t\t\t\t  <\/a> <\/h2>\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 1 & 2 Title End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 1 Meta Tag Start-->\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"zolo_blog_date\" style=\"color:#ffffff;\">\r\n\t\t\t\t\tf\u00e9vrier 16th, 2024\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 1 Meta Tag End--> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<!--Style 2 Meta Tag Start-->\r\n\t\t\t\t\t\t\t\t\t\t<!--Style 2 Meta Tag End--> \r\n\t\t\t\t\t<!--Style 2 Meta Tag Start-->\r\n\t\t\t\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t  \t\t\t\t  <!--Style 1 & 2 Blog Detail Area End--> \r\n\t\t\t\t  \r\n\t\t\t\t<\/div>\r\n\t\t\t  <\/div>\r\n\t\t\t  <!--Blog Box Area End-->\r\n\t\t\t  \r\n\t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t  \t\t\t<\/div>\r\n\t\t  <\/div>\r\n\t\t  <!-- .navigation -->\r\n\t\t  \r\n\t\t  \t\t  \r\n\t\t  <!-- .navigation END --> \r\n\t\t<\/div>\r\n\t\t<style>\r\n\t\t.zolo_blog_style14.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box{ padding:120px 0 120px 0;}\r\n\t\t\r\n\t\t.zolo_blog_style11.zoloblogstyleacp_2553290736a56efce696de .blog_layout_none .format-quote .zolo_blogcontent .zolo_blog_box,\r\n\t\t.zolo_blog_style10.zoloblogstyleacp_2553290736a56efce696de .blog_layout_none .format-quote .zolo_blogcontent .zolo_blog_box,\r\n\t\t.zolo_blog_style11.zoloblogstyleacp_2553290736a56efce696de .zolo_blogcontent .zolo_blog_box,\r\n\t\t.zolo_blog_style10.zoloblogstyleacp_2553290736a56efce696de .zolo_blogcontent .zolo_blog_box{ padding:35px;}\r\n\t\t\r\n\t\t.zolo_blog_style11.zoloblogstyleacp_2553290736a56efce696de .blog_layout_none .zolo_blogcontent .zolo_blog_box,\r\n\t\t.zolo_blog_style10.zoloblogstyleacp_2553290736a56efce696de .blog_layout_none .zolo_blogcontent .zolo_blog_box{ padding:0;}\r\n\t\t\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de.blog_layout_box_withoutpadding .zolo_blogcontent,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de.blog_layout_box .zolo_blogcontent{background:#ffffff;box-shadow: 0 0 2px #eeeeee;}\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de.blog_layout_box_withoutpadding .zolo_blogcontent:hover,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de.blog_layout_box .zolo_blogcontent:hover{box-shadow: 0 0 7px #eeeeee;}\r\n\t\t\r\n\t\t.zolo_blog_style11.zoloblogstyleacp_2553290736a56efce696de .blog_layout_box_withseparator .zolo_blogcontent,\r\n\t\t.zolo_blog_style10.zoloblogstyleacp_2553290736a56efce696de .blog_layout_box_withseparator .zolo_blogcontent,\r\n\t\t.zolo_blog_style11.zoloblogstyleacp_2553290736a56efce696de .blog_layout_box .zolo_blogcontent,\r\n\t\t.zolo_blog_style10.zoloblogstyleacp_2553290736a56efce696de .blog_layout_box .zolo_blogcontent{background:#ffffff;box-shadow: 0 0 2px #eeeeee;}\r\n\t\t\r\n\t\t.zolo_blog_style11.zoloblogstyleacp_2553290736a56efce696de .blog_layout_box_withseparator .zolo_blogcontent:hover,\r\n\t\t.zolo_blog_style10.zoloblogstyleacp_2553290736a56efce696de .blog_layout_box_withseparator .zolo_blogcontent:hover,\r\n\t\t.zolo_blog_style11.zoloblogstyleacp_2553290736a56efce696de .blog_layout_box .zolo_blogcontent:hover,\r\n\t\t.zolo_blog_style10.zoloblogstyleacp_2553290736a56efce696de .blog_layout_box .zolo_blogcontent:hover{box-shadow: 0 0 7px #eeeeee;}\r\n\t\t\r\n\t\t.zolo_blog_style15.zoloblogstyleacp_2553290736a56efce696de .post_content_wrapper:after{ border-color:#ffffff;}\r\n\t\t.zolo_blog_style15.zoloblogstyleacp_2553290736a56efce696de .zolo_blogcontent,\r\n\t\t.zolo_blog_style13.zoloblogstyleacp_2553290736a56efce696de .zolo_blogcontent,\r\n\t\t.zolo_blog_style12.zoloblogstyleacp_2553290736a56efce696de .zolo_blogcontent{background:#ffffff;box-shadow: 0 0 2px #eeeeee;}\r\n\t\t.zolo_blog_style15.zoloblogstyleacp_2553290736a56efce696de .zolo_blogcontent:hover,\r\n\t\t.zolo_blog_style13.zoloblogstyleacp_2553290736a56efce696de .zolo_blogcontent:hover,\r\n\t\t.zolo_blog_style12.zoloblogstyleacp_2553290736a56efce696de .zolo_blogcontent:hover{box-shadow: 0 0 7px #eeeeee;}\r\n\t\t.zolo_blog_style13.zoloblogstyleacp_2553290736a56efce696de .blog_entry_footer,\r\n\t\t.zolo_blog_style12.zoloblogstyleacp_2553290736a56efce696de .blog_entry_footer{ border-top:1px solid #f9f9f9;}\r\n\t\t.zolo_blog_style13.zoloblogstyleacp_2553290736a56efce696de .post_content_box,\r\n\t\t.zolo_blog_style12.zoloblogstyleacp_2553290736a56efce696de .post_content_box{background:#ffffff;}\r\n\t\t\r\n\t\t\r\n\t\t.zolo_blog_style12.zoloblogstyleacp_2553290736a56efce696de .blog_entry_footer .share-box li a,\r\n\t\t.zolo_blog_style12.zoloblogstyleacp_2553290736a56efce696de ul.apress_postmeta li a,\r\n\t\t.zolo_blog_style12.zoloblogstyleacp_2553290736a56efce696de ul.apress_postmeta li{color:#818181;}\r\n\t\t.zolo_blog_style12.zoloblogstyleacp_2553290736a56efce696de .blog_entry_footer .share-box li a:hover,\r\n\t\t.zolo_blog_style12.zoloblogstyleacp_2553290736a56efce696de ul.apress_postmeta li a:hover{color:#549ffc;}\r\n\t\t\r\n\t\t\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .categories-links a{color:#757575; }\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .categories-links a:hover{color:#549ffc;}\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .categories-links.rounded a,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .categories-links.box a{ background:#ffffff; border:1px solid #757575;}\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .categories-links.rounded a:hover,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .categories-links.box a:hover{ background:#ffffff; border:1px solid #549ffc;}\r\n\t\t\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .read_more_area a.read-more{ color:#757575;background:#ffffff; border:1px solid #757575;}\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .read_more_area a.read-more:hover{ color:#549ffc;background:#ffffff; border:1px solid #549ffc;}\r\n\t\t\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .read_more_area,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .share-box,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .post_title_area{text-align:left;}\r\n\t\t\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .share-box li a{color:#757575;background:#ffffff; border:1px solid #757575;\r\n\t\t-moz-border-radius:6px;\r\n\t\t-webkit-border-radius:6px;\r\n\t\t-ms-border-radius:6px;\r\n\t\t-o-border-radius:6px;\r\n\t\tborder-radius:6px;}\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .share-box li a:hover{color:#549ffc;background:#ffffff; border:1px solid #549ffc;}\r\n\t\t\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .share-box h4,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .post_title_area h2,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .post_title_area h2 a{ color:#ffffff; }\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .post_title_area h2{font-size:24px;padding-top:0px; padding-bottom:20px;}\r\n\t\t\r\n\t\t.zolo_blog_style13.zoloblogstyleacp_2553290736a56efce696de .blog_entry_footer,\r\n\t\t.zolo_blog_style13.zoloblogstyleacp_2553290736a56efce696de .blog_entry_footer .share-box li a,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de ul.apress_postmeta li a,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de ul.apress_postmeta li,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de ul.entry_meta_list li a,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de ul.entry_meta_list li{ color:#818181;}\r\n\t\t\r\n\t\t.zolo_blog_style13.zoloblogstyleacp_2553290736a56efce696de .blog_entry_footer .share-box li a:hover,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de ul.apress_postmeta li a:hover,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de ul.entry_meta_list li a:hover{ color:#549ffc;}\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t\t\t\t.zolo_blog_vertical.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box .overlay{ opacity:0;filter: alpha(opacity=0);}\r\n\t\t\t.zolo_blog_vertical.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box:hover .overlay{opacity:0.8;filter: alpha(opacity=80);background:#007f48;}\r\n\t\t\t\r\n\t\t\t\t\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t.zolo_blog_vertical.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box .zolo_blog_icons .zolo_blog_icon{background:rgba(10,0,0,0.24);}\r\n\t\t\r\n\t\t.zolo_blog_vertical.zoloblogstyleacp_2553290736a56efce696de  .zolo_blog_box .zolo_blog_icons .zolo_blog_icon:hover{background:rgba(10,0,0,0.24);}\r\n\t\t\r\n\t\t.zolo_blog_style8.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box:hover .zolo_blog_title{ color:#0187a0!important;}\r\n\t\t\r\n\t\t.zolo_blog_style8.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box .zolo_blog_thumb img,\r\n\t\t.zolo_blog_style3.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box .zolo_blog_thumb .overlay,\r\n\t\t.zolo_blog_style3.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box .zolo_blog_thumb img,\r\n\t\t.zolo_blog_style2.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box .zolo_blog_thumb .overlay,\r\n\t\t.zolo_blog_style2.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box .zolo_blog_thumb img,\r\n\t\t.zolo_blog_style1.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box .zolo_blog_thumb .overlay,\r\n\t\t.zolo_blog_style1.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box .zolo_blog_thumb img{ border-top-left-radius:0px;border-top-right-radius:0px;}\r\n\t\t\r\n\t\t.zolo_blog_style4.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box .zolo_blog_thumb .overlay,\r\n\t\t.zolo_blog_style4.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_box .zolo_blog_thumb img{ border-radius:0px;}\r\n\t\t\r\n\t\t.zolo_blog_style7.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_meta .zilla-likes:hover,\r\n\t\t.zolo_blog_style7.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_meta .zilla-likes.active,\r\n\t\t.zolo_blog_style7.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_meta a.zilla-likes,\r\n\t\t.zolo_blog_style6.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_meta .zilla-likes:hover,\r\n\t\t.zolo_blog_style6.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_meta .zilla-likes.active,\r\n\t\t.zolo_blog_style6.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_meta a.zilla-likes,\r\n\t\t.zolo_blog_style5.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_meta .zilla-likes:hover,\r\n\t\t.zolo_blog_style5.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_meta .zilla-likes.active,\r\n\t\t.zolo_blog_style5.zoloblogstyleacp_2553290736a56efce696de .zolo_blog_meta a.zilla-likes{color:;}\r\n\t\t\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .blog_load_more_cont a.btn_load_more{background:#549ffc;  color:#fff;border:1px solid #549ffc;}\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .blog_load_more_cont a.btn_load_more:hover{ background:#549ffc; color:#fff;border:1px solid #549ffc;}\r\n\t\t\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .page-numbers li a{background:#eeeeee;  color:#000000!important;border:1px solid #eeeeee!important;}\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .page-numbers li span,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .page-numbers li a:hover{background:#549ffc;color:#ffffff!important;border:1px solid #eeeeee!important;}\r\n\t\t\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .blog_layout_box_withseparator .apress_postmeta_area{ border-top:1px solid #f9f9f9;}\r\n\t\t\r\n\t\t\t\t\r\n\t\t\/*Filters CSS Start*\/\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .filters-button-group{ text-align:left;}\r\n\t\t\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .filters-button-group button.button{color:#fff;font-size:16px; line-height:16px;}\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .filters-button-group button.button.is-checked,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .filters-button-group button.button:hover{color:#fff;opacity:1}\r\n\t\t\r\n\t\t\r\n\t\t\t\t\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .filters-button-group button.button{background:#549ffc;border:1px solid #3174c8;\r\n\t\t-moz-border-radius:0px;\r\n\t\t-webkit-border-radius:0px;\r\n\t\t-ms-border-radius:0px;\r\n\t\t-o-border-radius:0px;\r\n\t\tborder-radius:0px;\r\n\t\t}\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .filters-button-group button.button.is-checked,\r\n\t\t.zoloblogstyleacp_2553290736a56efce696de .filters-button-group button.button:hover{background:#3174c8;border:1px solid #3174c8;}\r\n\t\t\r\n\t\t\t\t\r\n\t\t\r\n\t\t\/*Filters CSS End*\/\r\n\t\t\r\n\t\t@media (max-width:767px) {\r\n\t\t.zolo_blog_style15.zoloblogstyleacp_2553290736a56efce696de .post_content_wrapper:after{ border-bottom-color:#ffffff!important;}\r\n\t\t}\r\n\t\t<\/style>\r\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-row-text-color=\"dark\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row zolo_wpb_row vc_row-fluid partner-logos apress_row_class_20138716976a56efce6b7d6 vc_custom_1661316157546 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12 apress_col_id_13543826926a56efce6bbe3 hover_style_none\"><div class=\"layer vc_column-inner\"  ><div class=\"wpb_wrapper\">\t\r\n<div id=\"zolo_heading_element_4628412946a56efce6be99\" class=\"zolo_heading_element heading_style1 noanimation\" data-animation = \"No Animation\" data-delay = \"500\" style=\" text-align:center\"><div class=\"zolo_heading_element_text\"><h2 class=\"zolo-title\"><span class=\"title_text\" style=\"font-size: 40px; font-weight:bold; \">Nos partenaires<\/span><\/h2><\/div><\/div>\r\n<style>\r\n#zolo_heading_element_4628412946a56efce6be99 .zolo-title {}#zolo_heading_element_4628412946a56efce6be99 .zolo-sub-title {}#zolo_heading_element_4628412946a56efce6be99 .zolo-heading-delimiter {}\/*Design Your Won CSS Start*\/\r\n#zolo_heading_element_4628412946a56efce6be99 .zolo-title span.title_text{color:#0f7f4a;}\r\n\r\n\/*Design Your Won CSS End*\/\r\n#zolo_heading_element_4628412946a56efce6be99.heading_style11 .zolo-sub-title span.zolo-sub-title-text,\r\n#zolo_heading_element_4628412946a56efce6be99.heading_style12 .zolo-sub-title span.zolo-sub-title-text{ background:#f2f2f2; padding:7px 15px;}\r\n\r\n#zolo_heading_element_4628412946a56efce6be99 .delimiter_style_line { display:inline-block; border-bottom:3px solid ;width:80px;}\r\n\r\n#zolo_heading_element_4628412946a56efce6be99 .zolo_icon{ font-size:30px; color:;}\r\n#zolo_heading_element_4628412946a56efce6be99 .zolo_icon.circle_background,\r\n#zolo_heading_element_4628412946a56efce6be99 .zolo_icon.square_background{ background:#eeeeee;}\r\n\r\n#zolo_heading_element_4628412946a56efce6be99 .zolo_icon.design_your_own{ width:50px; height:50px;line-height:50px;background:#eeeeee;border:1px  #eaeaea;\r\n-moz-border-radius:300px;-webkit-border-radius:300px;-ms-border-radius:300px;-o-border-radius:300px;border-radius:300px;}\r\n\r\n\r\n#zolo_heading_element_4628412946a56efce6be99 .space_between_line_icon{ padding:0 20px; display:inline-block; position:relative;}\r\n\r\n#zolo_heading_element_4628412946a56efce6be99 .space_between_line_icon:before,\r\n#zolo_heading_element_4628412946a56efce6be99 .space_between_line_icon:after{border-bottom:3px solid ;width:80px;\r\n}\r\n<\/style>\r\n<\/div><\/div><\/div><div class=\"logos-flex wpb_column vc_column_container vc_col-sm-12 apress_col_id_20268470226a56efce6c1a1 hover_style_none\"><div class=\"layer vc_column-inner\"  ><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"https:\/\/agra.org\/\" target=\"_blank\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"85\" src=\"https:\/\/africafoodprize.org\/wp-content\/uploads\/2022\/09\/AGRA-logo-new.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"AGRA logo new\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 30px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Awardees stand to earn US$100,000&nbsp; H. E Jakaya Kikwete leads the Africa Food Prize committee Prize seeks nominations from fields such as technology, education, and policy advocacy Nairobi, 12th February<span class=\"read_more_area\"><a class=\"read-more\" href=\"https:\/\/africafoodprize.org\/fr\/africa-food-prize-2024-call-for-nominations-now-open\/\"> Read More <\/a><\/span>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/africafoodprize.org\/fr\/wp-json\/wp\/v2\/pages\/987"}],"collection":[{"href":"https:\/\/africafoodprize.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/africafoodprize.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/africafoodprize.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/africafoodprize.org\/fr\/wp-json\/wp\/v2\/comments?post=987"}],"version-history":[{"count":4,"href":"https:\/\/africafoodprize.org\/fr\/wp-json\/wp\/v2\/pages\/987\/revisions"}],"predecessor-version":[{"id":1435,"href":"https:\/\/africafoodprize.org\/fr\/wp-json\/wp\/v2\/pages\/987\/revisions\/1435"}],"wp:attachment":[{"href":"https:\/\/africafoodprize.org\/fr\/wp-json\/wp\/v2\/media?parent=987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}